{"id":78,"date":"2019-10-04T01:18:00","date_gmt":"2019-10-04T01:18:00","guid":{"rendered":"http:\/\/www.nyeusi.co\/?page_id=78"},"modified":"2024-03-24T02:53:17","modified_gmt":"2024-03-24T07:53:17","slug":"church-calendar","status":"publish","type":"page","link":"https:\/\/gatheringofchrist.org\/es\/church-calendar\/","title":{"rendered":"Calendario de la Iglesia"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div data-parent=\"true\" class=\"vc_row row-container\" id=\"row-unique-0\"><div class=\"row limit-width row-parent\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-12 single-internal-gutter\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"uncode_text_column\" ><div id=\"mec_skin_62\"\r\n     class=\"mec-wrap colorskin-custom   mec-full-calendar-wrap\">\r\n\r\n    <div class=\"mec-search-form mec-totalcal-box\">\r\n                                            <form id=\"mec_search_form_62\" class=\"mec-dropdown-wrap mec-dropdown-classic\" autocomplete=\"off\" action=\"\">\r\n                <div>\r\n\r\n                    \r\n                    <div class=\"mec-dropdown-wrap\">\r\n                                                    <div class=\"mec-dropdown-search\"><i class=\"mec-sl-folder\"><\/i><select name=\" \" id=\"mec_sf_category_62\" class=\"postform\">\n\t<option value=\"\" selected=\"selected\">Categor\u00eda<\/option>\n\t<option class=\"level-0\" value=\"280\">Academy<\/option>\n\t<option class=\"level-0\" value=\"245\">D\u00eda festivo<\/option>\n\t<option class=\"level-0\" value=\"279\">Programa de radio<\/option>\n\t<option class=\"level-0\" value=\"18\">Clase sab\u00e1tica<\/option>\n\t<option class=\"level-0\" value=\"278\">Estaciones<\/option>\n<\/select>\n<\/div>                                                                                                                                                                    <\/div>\r\n                <\/div>\r\n                                <div>\r\n                                                        <\/div>\r\n                <div class=\"mec-full-calendar-search-ends\">\r\n                                            <div class=\"mec-text-input-search\"><i class=\"mec-sl-magnifier\"><\/i>\r\n                    <input type=\"search\" value=\"\" id=\"mec_sf_s_62\" placeholder=\"Search\" title=\"Search\" \/>\r\n                <\/div>                                                                <div class=\"mec-date-search\"><input type=\"hidden\" id=\"mec-filter-none\" value=\"Seleccionar\"><i class=\"mec-sl-calendar\"><\/i>\r\n                    <select id=\"mec_sf_month_62\" title=\"Filtrar por mes\">\r\n                        <option value=\"\">Select Month<\/option><option value=\"01\">enero<\/option><option value=\"02\">febrero<\/option><option value=\"03\">marzo<\/option><option value=\"04\">abril<\/option><option value=\"05\">mayo<\/option><option value=\"06\">junio<\/option><option value=\"07\">julio<\/option><option value=\"08\">agosto<\/option><option value=\"09\" selected>septiembre<\/option><option value=\"10\">octubre<\/option><option value=\"11\">noviembre<\/option><option value=\"12\">diciembre<\/option><\/select><select id=\"mec_sf_year_62\" title=\"Year Filter\"><option value=\"\">Select Year<\/option><option value=\"2021\">2021<\/option><option value=\"2022\">2022<\/option><option value=\"2023\">2023<\/option><option value=\"2024\">2024<\/option><option value=\"2025\">2025<\/option><option value=\"2026\" selected>2026<\/option><option value=\"2027\">2027<\/option><option value=\"2028\">2028<\/option><option value=\"2029\">2029<\/option><option value=\"2030\">2030<\/option><option value=\"2031\">2031<\/option><option value=\"2032\">2032<\/option><option value=\"2033\">2033<\/option><option value=\"2034\">2034<\/option><option value=\"2035\">2035<\/option><option value=\"2036\">2036<\/option><option value=\"2037\">2037<\/option><option value=\"2038\">2038<\/option><option value=\"2039\">2039<\/option><option value=\"2040\">2040<\/option><option value=\"2041\">2041<\/option><option value=\"2042\">2042<\/option><option value=\"2043\">2043<\/option><option value=\"2044\">2044<\/option><option value=\"2045\">2045<\/option><option value=\"2046\">2046<\/option><option value=\"2047\">2047<\/option><option value=\"2048\">2048<\/option><option value=\"2049\">2049<\/option><option value=\"2050\">2050<\/option><option value=\"2051\">2051<\/option><option value=\"2052\">2052<\/option><option value=\"2053\">2053<\/option><option value=\"2054\">2054<\/option><option value=\"2055\">2055<\/option><option value=\"2056\">2056<\/option><option value=\"2057\">2057<\/option><option value=\"2058\">2058<\/option><option value=\"2059\">2059<\/option><option value=\"2060\">2060<\/option><option value=\"2061\">2061<\/option><option value=\"2062\">2062<\/option><option value=\"2063\">2063<\/option><option value=\"2064\">2064<\/option><option value=\"2065\">2065<\/option><option value=\"2066\">2066<\/option><option value=\"2067\">2067<\/option><option value=\"2068\">2068<\/option><option value=\"2069\">2069<\/option><option value=\"2070\">2070<\/option><option value=\"2071\">2071<\/option><option value=\"2072\">2072<\/option><option value=\"2073\">2073<\/option><option value=\"2074\">2074<\/option><option value=\"2075\">2075<\/option><option value=\"2076\">2076<\/option><option value=\"2077\">2077<\/option><option value=\"2078\">2078<\/option><option value=\"2079\">2079<\/option><option value=\"2080\">2080<\/option><option value=\"2081\">2081<\/option><option value=\"2082\">2082<\/option><option value=\"2083\">2083<\/option><option value=\"2084\">2084<\/option><option value=\"2085\">2085<\/option><option value=\"2086\">2086<\/option><option value=\"2087\">2087<\/option><option value=\"2088\">2088<\/option><option value=\"2089\">2089<\/option><option value=\"2090\">2090<\/option><option value=\"2091\">2091<\/option><option value=\"2092\">2092<\/option><option value=\"2093\">2093<\/option><option value=\"2094\">2094<\/option><option value=\"2095\">2095<\/option><option value=\"2096\">2096<\/option><option value=\"2097\">2097<\/option><option value=\"2098\">2098<\/option><option value=\"2099\">2099<\/option><option value=\"2100\">2100<\/option><option value=\"2101\">2101<\/option><option value=\"2102\">2102<\/option><option value=\"2103\">2103<\/option><option value=\"2104\">2104<\/option><option value=\"2105\">2105<\/option><option value=\"2106\">2106<\/option><option value=\"2107\">2107<\/option><option value=\"2108\">2108<\/option><option value=\"2109\">2109<\/option><option value=\"2110\">2110<\/option><option value=\"2111\">2111<\/option><option value=\"2112\">2112<\/option><option value=\"2113\">2113<\/option><option value=\"2114\">2114<\/option><option value=\"2115\">2115<\/option><option value=\"2116\">2116<\/option><option value=\"2117\">2117<\/option><option value=\"2118\">2118<\/option><option value=\"2119\">2119<\/option><option value=\"2120\">2120<\/option><option value=\"2121\">2121<\/option><option value=\"2122\">2122<\/option><option value=\"2123\">2123<\/option><option value=\"2124\">2124<\/option><option value=\"2125\">2125<\/option><option value=\"2126\">2126<\/option><option value=\"2127\">2127<\/option><option value=\"2128\">2128<\/option><option value=\"2129\">2129<\/option><option value=\"2130\">2130<\/option><option value=\"2131\">2131<\/option><option value=\"2132\">2132<\/option><option value=\"2133\">2133<\/option><option value=\"2134\">2134<\/option><option value=\"2135\">2135<\/option><option value=\"2136\">2136<\/option><option value=\"2137\">2137<\/option><option value=\"2138\">2138<\/option><option value=\"2139\">2139<\/option><option value=\"2140\">2140<\/option><option value=\"2141\">2141<\/option><option value=\"2142\">2142<\/option><option value=\"2143\">2143<\/option><option value=\"2144\">2144<\/option><option value=\"2145\">2145<\/option><option value=\"2146\">2146<\/option><option value=\"2147\">2147<\/option><option value=\"2148\">2148<\/option><option value=\"2149\">2149<\/option><option value=\"2150\">2150<\/option><option value=\"2151\">2151<\/option><option value=\"2152\">2152<\/option><option value=\"2153\">2153<\/option><option value=\"2154\">2154<\/option><option value=\"2155\">2155<\/option><option value=\"2156\">2156<\/option><option value=\"2157\">2157<\/option><option value=\"2158\">2158<\/option><option value=\"2159\">2159<\/option><option value=\"2160\">2160<\/option><option value=\"2161\">2161<\/option><option value=\"2162\">2162<\/option><option value=\"2163\">2163<\/option><option value=\"2164\">2164<\/option><option value=\"2165\">2165<\/option><option value=\"2166\">2166<\/option><option value=\"2167\">2167<\/option><option value=\"2168\">2168<\/option><option value=\"2169\">2169<\/option><option value=\"2170\">2170<\/option><option value=\"2171\">2171<\/option><option value=\"2172\">2172<\/option><option value=\"2173\">2173<\/option><option value=\"2174\">2174<\/option><option value=\"2175\">2175<\/option><option value=\"2176\">2176<\/option><option value=\"2177\">2177<\/option><option value=\"2178\">2178<\/option><option value=\"2179\">2179<\/option><option value=\"2180\">2180<\/option><option value=\"2181\">2181<\/option><option value=\"2182\">2182<\/option><option value=\"2183\">2183<\/option><option value=\"2184\">2184<\/option><option value=\"2185\">2185<\/option><option value=\"2186\">2186<\/option><option value=\"2187\">2187<\/option><option value=\"2188\">2188<\/option><option value=\"2189\">2189<\/option><option value=\"2190\">2190<\/option><option value=\"2191\">2191<\/option><option value=\"2192\">2192<\/option><option value=\"2193\">2193<\/option><option value=\"2194\">2194<\/option><option value=\"2195\">2195<\/option><option value=\"2196\">2196<\/option><option value=\"2197\">2197<\/option><option value=\"2198\">2198<\/option><option value=\"2199\">2199<\/option><option value=\"2200\">2200<\/option><option value=\"2201\">2201<\/option><option value=\"2202\">2202<\/option><option value=\"2203\">2203<\/option><option value=\"2204\">2204<\/option><option value=\"2205\">2205<\/option><option value=\"2206\">2206<\/option><option value=\"2207\">2207<\/option><option value=\"2208\">2208<\/option><option value=\"2209\">2209<\/option><option value=\"2210\">2210<\/option><option value=\"2211\">2211<\/option><option value=\"2212\">2212<\/option><option value=\"2213\">2213<\/option><option value=\"2214\">2214<\/option><option value=\"2215\">2215<\/option><option value=\"2216\">2216<\/option><option value=\"2217\">2217<\/option><option value=\"2218\">2218<\/option><option value=\"2219\">2219<\/option><option value=\"2220\">2220<\/option><option value=\"2221\">2221<\/option><option value=\"2222\">2222<\/option><option value=\"2223\">2223<\/option><option value=\"2224\">2224<\/option><option value=\"2225\">2225<\/option><option value=\"2226\">2226<\/option><option value=\"2227\">2227<\/option><option value=\"2228\">2228<\/option><option value=\"2229\">2229<\/option><option value=\"2230\">2230<\/option><option value=\"2231\">2231<\/option><option value=\"2232\">2232<\/option><option value=\"2233\">2233<\/option><option value=\"2234\">2234<\/option><option value=\"2235\">2235<\/option><option value=\"2236\">2236<\/option><option value=\"2237\">2237<\/option><option value=\"2238\">2238<\/option><option value=\"2239\">2239<\/option><option value=\"2240\">2240<\/option><option value=\"2241\">2241<\/option><option value=\"2242\">2242<\/option><option value=\"2243\">2243<\/option><option value=\"2244\">2244<\/option><option value=\"2245\">2245<\/option><option value=\"2246\">2246<\/option><option value=\"2247\">2247<\/option><option value=\"2248\">2248<\/option><option value=\"2249\">2249<\/option><option value=\"2250\">2250<\/option><option value=\"2251\">2251<\/option><option value=\"2252\">2252<\/option><option value=\"2253\">2253<\/option><option value=\"2254\">2254<\/option><option value=\"2255\">2255<\/option><option value=\"2256\">2256<\/option><option value=\"2257\">2257<\/option><option value=\"2258\">2258<\/option><option value=\"2259\">2259<\/option><option value=\"2260\">2260<\/option><option value=\"2261\">2261<\/option><option value=\"2262\">2262<\/option><option value=\"2263\">2263<\/option><option value=\"2264\">2264<\/option><option value=\"2265\">2265<\/option><option value=\"2266\">2266<\/option><option value=\"2267\">2267<\/option><option value=\"2268\">2268<\/option><option value=\"2269\">2269<\/option><option value=\"2270\">2270<\/option><option value=\"2271\">2271<\/option><option value=\"2272\">2272<\/option><option value=\"2273\">2273<\/option><option value=\"2274\">2274<\/option><option value=\"2275\">2275<\/option><option value=\"2276\">2276<\/option><option value=\"2277\">2277<\/option><option value=\"2278\">2278<\/option><option value=\"2279\">2279<\/option><option value=\"2280\">2280<\/option><option value=\"2281\">2281<\/option><option value=\"2282\">2282<\/option><option value=\"2283\">2283<\/option><option value=\"2284\">2284<\/option><option value=\"2285\">2285<\/option><option value=\"2286\">2286<\/option><option value=\"2287\">2287<\/option><option value=\"2288\">2288<\/option><option value=\"2289\">2289<\/option><option value=\"2290\">2290<\/option><option value=\"2291\">2291<\/option><option value=\"2292\">2292<\/option><option value=\"2293\">2293<\/option><option value=\"2294\">2294<\/option><option value=\"2295\">2295<\/option><option value=\"2296\">2296<\/option><option value=\"2297\">2297<\/option><option value=\"2298\">2298<\/option><option value=\"2299\">2299<\/option><option value=\"2300\">2300<\/option><option value=\"2301\">2301<\/option><option value=\"2302\">2302<\/option><option value=\"2303\">2303<\/option><option value=\"2304\">2304<\/option><option value=\"2305\">2305<\/option><option value=\"2306\">2306<\/option><option value=\"2307\">2307<\/option><option value=\"2308\">2308<\/option><option value=\"2309\">2309<\/option><option value=\"2310\">2310<\/option><option value=\"2311\">2311<\/option><option value=\"2312\">2312<\/option><option value=\"2313\">2313<\/option><option value=\"2314\">2314<\/option><option value=\"2315\">2315<\/option><option value=\"2316\">2316<\/option><option value=\"2317\">2317<\/option><option value=\"2318\">2318<\/option><option value=\"2319\">2319<\/option><option value=\"2320\">2320<\/option><option value=\"2321\">2321<\/option><option value=\"2322\">2322<\/option><option value=\"2323\">2323<\/option><option value=\"2324\">2324<\/option><option value=\"2325\">2325<\/option><option value=\"2326\">2326<\/option><option value=\"2327\">2327<\/option><option value=\"2328\">2328<\/option><option value=\"2329\">2329<\/option><option value=\"2330\">2330<\/option><option value=\"2331\">2331<\/option><option value=\"2332\">2332<\/option><option value=\"2333\">2333<\/option><option value=\"2334\">2334<\/option><option value=\"2335\">2335<\/option><option value=\"2336\">2336<\/option><option value=\"2337\">2337<\/option><option value=\"2338\">2338<\/option><option value=\"2339\">2339<\/option><option value=\"2340\">2340<\/option><option value=\"2341\">2341<\/option><option value=\"2342\">2342<\/option><option value=\"2343\">2343<\/option><option value=\"2344\">2344<\/option><option value=\"2345\">2345<\/option><option value=\"2346\">2346<\/option><option value=\"2347\">2347<\/option><option value=\"2348\">2348<\/option><option value=\"2349\">2349<\/option><option value=\"2350\">2350<\/option><option value=\"2351\">2351<\/option><option value=\"2352\">2352<\/option><option value=\"2353\">2353<\/option><option value=\"2354\">2354<\/option><option value=\"2355\">2355<\/option><option value=\"2356\">2356<\/option><option value=\"2357\">2357<\/option><option value=\"2358\">2358<\/option><option value=\"2359\">2359<\/option><option value=\"2360\">2360<\/option><option value=\"2361\">2361<\/option><option value=\"2362\">2362<\/option><option value=\"2363\">2363<\/option><option value=\"2364\">2364<\/option><option value=\"2365\">2365<\/option><option value=\"2366\">2366<\/option><option value=\"2367\">2367<\/option><option value=\"2368\">2368<\/option><option value=\"2369\">2369<\/option><option value=\"2370\">2370<\/option><option value=\"2371\">2371<\/option><option value=\"2372\">2372<\/option><option value=\"2373\">2373<\/option><option value=\"2374\">2374<\/option><option value=\"2375\">2375<\/option><option value=\"2376\">2376<\/option><option value=\"2377\">2377<\/option><option value=\"2378\">2378<\/option><option value=\"2379\">2379<\/option><option value=\"2380\">2380<\/option><option value=\"2381\">2381<\/option><option value=\"2382\">2382<\/option><option value=\"2383\">2383<\/option><option value=\"2384\">2384<\/option><option value=\"2385\">2385<\/option><option value=\"2386\">2386<\/option><option value=\"2387\">2387<\/option><option value=\"2388\">2388<\/option><option value=\"2389\">2389<\/option><option value=\"2390\">2390<\/option><option value=\"2391\">2391<\/option><option value=\"2392\">2392<\/option><option value=\"2393\">2393<\/option><\/select><\/div>                                                                                <div class=\"mec-tab-loader\">\r\n                        <div class=\"mec-totalcal-view\">\r\n                                                        <span\r\n                                class=\"mec-totalcal-monthlyview mec-totalcalview-selected\"\r\n                                data-skin=\"monthly\">Mensualmente<\/span>                            <span\r\n                                class=\"mec-totalcal-weeklyview\"\r\n                                data-skin=\"weekly\">Semanalmente<\/span>                            <span\r\n                                class=\"mec-totalcal-dailyview\"\r\n                                data-skin=\"daily\">Diariamente<\/span>                            <span\r\n                                class=\"mec-totalcal-listview\"\r\n                                data-skin=\"list\">Lista<\/span>                            <span\r\n                                class=\"mec-totalcal-gridview\"\r\n                                data-skin=\"grid\">Vista cuadr\u00edcula<\/span>                            <span\r\n                                class=\"mec-totalcal-tileview\"\r\n                                data-skin=\"tile\">Vista de Horario<\/span>                        <\/div>\r\n                    <\/div>\r\n                <\/div>\r\n            <input type=\"hidden\" name=\"trp-form-language\" value=\"es\"\/><\/form>\r\n            <\/div>\r\n\r\n    <div id=\"mec_full_calendar_container_62\" class=\"mec-full-calendar-skin-container\">\r\n        <div id=\"mec_skin_62\" class=\"mec-wrap colorskin-custom\">\r\n\r\n    \r\n    <div class=\"mec-calendar\" id=\"mec_skin_events_62_full\">\r\n        <div class=\"mec-calendar-topsec\">        <div class=\"mec-calendar-side mec-clear\">\r\n                        <div class=\"mec-skin-monthly-view-month-navigator-container\">\r\n                <div class=\"mec-month-navigator\" id=\"mec_month_navigator_62_202609\"><div class=\"mec-previous-month mec-load-month mec-previous-month\" data-mec-year=\"2026\" data-mec-month=\"08\"><a href=\"#\" class=\"mec-load-month-link\"><i class=\"mec-sl-angle-left\"><\/i> agosto<\/a><\/div><div class=\"mec-calendar-header\"><h2>septiembre 2026<\/h2><\/div><div class=\"mec-next-month mec-load-month mec-next-month\" data-mec-year=\"2026\" data-mec-month=\"10\"><a href=\"#\" class=\"mec-load-month-link\">octubre <i class=\"mec-sl-angle-right\"><\/i><\/a><\/div><\/div>\r\n            <\/div>\r\n            \r\n            <div class=\"mec-calendar-table\" id=\"mec_skin_events_62\">\r\n                <div class=\"mec-month-container mec-month-container-selected\" id=\"mec_monthly_view_month_62_202609\" data-month-id=\"202609\"><dl class=\"mec-calendar-table-head\"><dt class=\"mec-calendar-day-head\">LU<\/dt><dt class=\"mec-calendar-day-head\">MA<\/dt><dt class=\"mec-calendar-day-head\">MI<\/dt><dt class=\"mec-calendar-day-head\">JU<\/dt><dt class=\"mec-calendar-day-head\">VI<\/dt><dt class=\"mec-calendar-day-head\">SA<\/dt><dt class=\"mec-calendar-day-head\">DO<\/dt><\/dl><dl class=\"mec-calendar-row\">\r\n    <dt class=\"mec-calendar-day mec-has-event mec-table-nullday\" data-mec-cell=\"20260831\" data-day=\"31\" data-month=\"202609\"><a href=\"#\" class=\"mec-has-event-a\">31<\/a><\/dt><dt class=\"mec-calendar-day\" data-mec-cell=\"20260901\" data-day=\"1\" data-month=\"202609\">1<\/dt><\/dt><dt class=\"mec-calendar-day mec-has-event  mec-selected-day\" data-mec-cell=\"20260902\" data-day=\"2\" data-month=\"202609\"><a href=\"#\" class=\"mec-has-event-a\">2<\/a><\/dt><\/dt><dt class=\"mec-calendar-day\" data-mec-cell=\"20260903\" data-day=\"3\" data-month=\"202609\">3<\/dt><\/dt><dt class=\"mec-calendar-day mec-has-event\" data-mec-cell=\"20260904\" data-day=\"4\" data-month=\"202609\"><a href=\"#\" class=\"mec-has-event-a\">4<\/a><\/dt><\/dt><dt class=\"mec-calendar-day mec-has-event\" data-mec-cell=\"20260905\" data-day=\"5\" data-month=\"202609\"><a href=\"#\" class=\"mec-has-event-a\">5<\/a><\/dt><\/dt><dt class=\"mec-calendar-day\" data-mec-cell=\"20260906\" data-day=\"6\" data-month=\"202609\">6<\/dt><\/dt><\/dl><dl class=\"mec-calendar-row\"><dt class=\"mec-calendar-day mec-has-event\" data-mec-cell=\"20260907\" data-day=\"7\" data-month=\"202609\"><a href=\"#\" class=\"mec-has-event-a\">7<\/a><\/dt><\/dt><dt class=\"mec-calendar-day mec-has-event\" data-mec-cell=\"20260908\" data-day=\"8\" data-month=\"202609\"><a href=\"#\" class=\"mec-has-event-a\">8<\/a><\/dt><\/dt><dt class=\"mec-calendar-day mec-has-event\" data-mec-cell=\"20260909\" data-day=\"9\" data-month=\"202609\"><a href=\"#\" class=\"mec-has-event-a\">9<\/a><\/dt><\/dt><dt class=\"mec-calendar-day\" data-mec-cell=\"20260910\" data-day=\"10\" data-month=\"202609\">10<\/dt><\/dt><dt class=\"mec-calendar-day mec-has-event\" data-mec-cell=\"20260911\" data-day=\"11\" data-month=\"202609\"><a href=\"#\" class=\"mec-has-event-a\">11<\/a><\/dt><\/dt><dt class=\"mec-calendar-day mec-has-event\" data-mec-cell=\"20260912\" data-day=\"12\" data-month=\"202609\"><a href=\"#\" class=\"mec-has-event-a\">12<\/a><\/dt><\/dt><dt class=\"mec-calendar-day mec-has-event\" data-mec-cell=\"20260913\" data-day=\"13\" data-month=\"202609\"><a href=\"#\" class=\"mec-has-event-a\">13<\/a><\/dt><\/dt><\/dl><dl class=\"mec-calendar-row\"><dt class=\"mec-calendar-day mec-has-event\" data-mec-cell=\"20260914\" data-day=\"14\" data-month=\"202609\"><a href=\"#\" class=\"mec-has-event-a\">14<\/a><\/dt><\/dt><dt class=\"mec-calendar-day mec-has-event\" data-mec-cell=\"20260915\" data-day=\"15\" data-month=\"202609\"><a href=\"#\" class=\"mec-has-event-a\">15<\/a><\/dt><\/dt><dt class=\"mec-calendar-day mec-has-event\" data-mec-cell=\"20260916\" data-day=\"16\" data-month=\"202609\"><a href=\"#\" class=\"mec-has-event-a\">16<\/a><\/dt><\/dt><dt class=\"mec-calendar-day mec-has-event\" data-mec-cell=\"20260917\" data-day=\"17\" data-month=\"202609\"><a href=\"#\" class=\"mec-has-event-a\">17<\/a><\/dt><\/dt><dt class=\"mec-calendar-day mec-has-event\" data-mec-cell=\"20260918\" data-day=\"18\" data-month=\"202609\"><a href=\"#\" class=\"mec-has-event-a\">18<\/a><\/dt><\/dt><dt class=\"mec-calendar-day mec-has-event\" data-mec-cell=\"20260919\" data-day=\"19\" data-month=\"202609\"><a href=\"#\" class=\"mec-has-event-a\">19<\/a><\/dt><\/dt><dt class=\"mec-calendar-day\" data-mec-cell=\"20260920\" data-day=\"20\" data-month=\"202609\">20<\/dt><\/dt><\/dl><dl class=\"mec-calendar-row\"><dt class=\"mec-calendar-day mec-has-event\" data-mec-cell=\"20260921\" data-day=\"21\" data-month=\"202609\"><a href=\"#\" class=\"mec-has-event-a\">21<\/a><\/dt><\/dt><dt class=\"mec-calendar-day\" data-mec-cell=\"20260922\" data-day=\"22\" data-month=\"202609\">22<\/dt><\/dt><dt class=\"mec-calendar-day mec-has-event\" data-mec-cell=\"20260923\" data-day=\"23\" data-month=\"202609\"><a href=\"#\" class=\"mec-has-event-a\">23<\/a><\/dt><\/dt><dt class=\"mec-calendar-day\" data-mec-cell=\"20260924\" data-day=\"24\" data-month=\"202609\">24<\/dt><\/dt><dt class=\"mec-calendar-day mec-has-event\" data-mec-cell=\"20260925\" data-day=\"25\" data-month=\"202609\"><a href=\"#\" class=\"mec-has-event-a\">25<\/a><\/dt><\/dt><dt class=\"mec-calendar-day mec-has-event\" data-mec-cell=\"20260926\" data-day=\"26\" data-month=\"202609\"><a href=\"#\" class=\"mec-has-event-a\">26<\/a><\/dt><\/dt><dt class=\"mec-calendar-day\" data-mec-cell=\"20260927\" data-day=\"27\" data-month=\"202609\">27<\/dt><\/dt><\/dl><dl class=\"mec-calendar-row\"><dt class=\"mec-calendar-day mec-has-event\" data-mec-cell=\"20260928\" data-day=\"28\" data-month=\"202609\"><a href=\"#\" class=\"mec-has-event-a\">28<\/a><\/dt><\/dt><dt class=\"mec-calendar-day\" data-mec-cell=\"20260929\" data-day=\"29\" data-month=\"202609\">29<\/dt><\/dt><dt class=\"mec-calendar-day mec-has-event\" data-mec-cell=\"20260930\" data-day=\"30\" data-month=\"202609\"><a href=\"#\" class=\"mec-has-event-a\">30<\/a><\/dt><\/dt><dt class=\"mec-table-nullday\">1<\/dt><dt class=\"mec-calendar-day mec-has-event mec-table-nullday\" data-mec-cell=\"20261002\" data-day=\"2\" data-month=\"202609\"><a href=\"#\" class=\"mec-has-event-a\">2<\/a><\/dt><dt class=\"mec-calendar-day mec-has-event mec-table-nullday\" data-mec-cell=\"20261003\" data-day=\"3\" data-month=\"202609\"><a href=\"#\" class=\"mec-has-event-a\">3<\/a><\/dt><dt class=\"mec-table-nullday\">4<\/dt><\/dl>\r\n<\/div>\r\n            <\/div>\r\n\r\n                    <\/div>\r\n        <div class=\"mec-calendar-events-side mec-clear\"><div class=\"mec-month-side\" id=\"mec_month_side_62_202609\"><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-62-20260831\" data-mec-cell=\"20260831\" ><h6 class=\"mec-table-side-title\">Eventos para agosto<\/h6><h3 class=\"mec-color mec-table-side-day\"> 31<\/h3><article class=\"mec-past-event mec-event-article\"><div class=\"mec-event-image\"><\/div><div class=\"mec-monthly-contents\" style=\"width: 100%\"><div class=\"mec-event-time mec-color\"><i class=\"mec-sl-clock-o\"><\/i> Evento de todo el d\u00eda<\/div><h4 class=\"mec-event-title\"><a class=\"mec-color-hover\" data-event-id=\"19056\" href=\"https:\/\/gatheringofchrist.org\/es\/events\/restoring-the-daughters-of-zion\/\" target=\"_self\" rel=\"noopener\">Restaurando a las Hijas de Si\u00f3n<\/a><span class=\"event-color\" style=\"background: #a3b745\"><\/span><\/h4><div class=\"mec-event-detail\">\r\n                        <div class=\"mec-event-loc-place\"><\/div>\r\n                        \r\n                    <\/div><\/div><div style=\"clear:both\"><\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-62-20260901\" data-mec-cell=\"20260901\" ><h6 class=\"mec-table-side-title\">Eventos para septiembre<\/h6><h3 class=\"mec-color mec-table-side-day\"> 1er<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Sin eventos<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-62-20260902\" data-mec-cell=\"20260902\"  style=\"display: block;\"><h6 class=\"mec-table-side-title\">Eventos para septiembre<\/h6><h3 class=\"mec-color mec-table-side-day\"> 2do<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-image\"><\/div><div class=\"mec-monthly-contents\" style=\"width: 100%\"><div class=\"mec-event-time mec-color\"><i class=\"mec-sl-clock-o\"><\/i> 8:00 am - 6:00 pm<\/div><h4 class=\"mec-event-title\"><a class=\"mec-color-hover\" data-event-id=\"18562\" href=\"http:\/\/www.blogtalkradio.com\/gocchurch\" target=\"_self\" rel=\"noopener\">Motor de B\u00fasqueda Internacional<\/a><span class=\"event-color\" style=\"background: #a3b745\"><\/span><\/h4><div class=\"mec-event-detail\">\r\n                        <div class=\"mec-event-loc-place\"><\/div>\r\n                        \r\n                    <\/div><\/div><div style=\"clear:both\"><\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-62-20260903\" data-mec-cell=\"20260903\" ><h6 class=\"mec-table-side-title\">Eventos para septiembre<\/h6><h3 class=\"mec-color mec-table-side-day\"> 3er<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Sin eventos<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-62-20260904\" data-mec-cell=\"20260904\" ><h6 class=\"mec-table-side-title\">Eventos para septiembre<\/h6><h3 class=\"mec-color mec-table-side-day\"> 4to<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-image\"><\/div><div class=\"mec-monthly-contents\" style=\"width: 100%\"><div class=\"mec-event-time mec-color\"><i class=\"mec-sl-clock-o\"><\/i> Evento de todo el d\u00eda<\/div><h4 class=\"mec-event-title\"><a class=\"mec-color-hover\" data-event-id=\"19057\" href=\"https:\/\/gatheringofchrist.org\/es\/events\/coming-out-of-bablyon\/\" target=\"_self\" rel=\"noopener\">Saliendo de Babilonia<\/a><span class=\"event-color\" style=\"background: #a3b745\"><\/span><\/h4><div class=\"mec-event-detail\">\r\n                        <div class=\"mec-event-loc-place\"><\/div>\r\n                        \r\n                    <\/div><\/div><div style=\"clear:both\"><\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-62-20260905\" data-mec-cell=\"20260905\" ><h6 class=\"mec-table-side-title\">Eventos para septiembre<\/h6><h3 class=\"mec-color mec-table-side-day\"> 5to<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-image\"><\/div><div class=\"mec-monthly-contents\" style=\"width: 100%\"><div class=\"mec-event-time mec-color\"><i class=\"mec-sl-clock-o\"><\/i> Evento de todo el d\u00eda<\/div><h4 class=\"mec-event-title\"><a class=\"mec-color-hover\" data-event-id=\"18558\" href=\"https:\/\/gatheringofchrist.org\/es\/events\/sabbath-class\/\" target=\"_self\" rel=\"noopener\">Clase sab\u00e1tica<\/a><span class=\"event-color\" style=\"background: #fdd700\"><\/span><\/h4><div class=\"mec-event-detail\">\r\n                        <div class=\"mec-event-loc-place\"><\/div>\r\n                        \r\n                    <\/div><\/div><div style=\"clear:both\"><\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-62-20260906\" data-mec-cell=\"20260906\" ><h6 class=\"mec-table-side-title\">Eventos para septiembre<\/h6><h3 class=\"mec-color mec-table-side-day\"> 6to<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Sin eventos<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-62-20260907\" data-mec-cell=\"20260907\" ><h6 class=\"mec-table-side-title\">Eventos para septiembre<\/h6><h3 class=\"mec-color mec-table-side-day\"> 7mo<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-image\"><\/div><div class=\"mec-monthly-contents\" style=\"width: 100%\"><div class=\"mec-event-time mec-color\"><i class=\"mec-sl-clock-o\"><\/i> Evento de todo el d\u00eda<\/div><h4 class=\"mec-event-title\"><a class=\"mec-color-hover\" data-event-id=\"19056\" href=\"https:\/\/gatheringofchrist.org\/es\/events\/restoring-the-daughters-of-zion\/\" target=\"_self\" rel=\"noopener\">Restaurando a las Hijas de Si\u00f3n<\/a><span class=\"event-color\" style=\"background: #a3b745\"><\/span><\/h4><div class=\"mec-event-detail\">\r\n                        <div class=\"mec-event-loc-place\"><\/div>\r\n                        \r\n                    <\/div><\/div><div style=\"clear:both\"><\/div><\/article><article class=\"mec-event-article\"><div class=\"mec-event-image\"><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/gatheringofchrist.org\/wp-content\/uploads\/2021\/04\/AdobeStock_99832137-1-scaled-300x300.jpeg\" class=\"attachment-thumblist size-thumblist wp-post-image\" alt=\"\" data-mec-postid=\"18271\" \/><\/div><div class=\"mec-monthly-contents\" style=\"width: calc(100% - 85px)\"><div class=\"mec-event-time mec-color\"><i class=\"mec-sl-clock-o\"><\/i> 6:00 pm - 12:00 am<\/div><h4 class=\"mec-event-title\"><a class=\"mec-color-hover\" data-event-id=\"18271\" href=\"https:\/\/gatheringofchrist.org\/es\/events\/day-of-atonement\/\" target=\"_self\" rel=\"noopener\">D\u00eda de la expiaci\u00f3n<\/a><\/h4><div class=\"mec-event-detail\">\r\n                        <div class=\"mec-event-loc-place\"><\/div>\r\n                        \r\n                    <\/div><\/div><div style=\"clear:both\"><\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-62-20260908\" data-mec-cell=\"20260908\" ><h6 class=\"mec-table-side-title\">Eventos para septiembre<\/h6><h3 class=\"mec-color mec-table-side-day\"> octavo<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-image\"><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/gatheringofchrist.org\/wp-content\/uploads\/2021\/04\/AdobeStock_99832137-1-scaled-300x300.jpeg\" class=\"attachment-thumblist size-thumblist wp-post-image\" alt=\"\" data-mec-postid=\"18271\" \/><\/div><div class=\"mec-monthly-contents\" style=\"width: calc(100% - 85px)\"><div class=\"mec-event-time mec-color\"><i class=\"mec-sl-clock-o\"><\/i> 12:00 am - 6:00 pm<\/div><h4 class=\"mec-event-title\"><a class=\"mec-color-hover\" data-event-id=\"18271\" href=\"https:\/\/gatheringofchrist.org\/es\/events\/day-of-atonement\/\" target=\"_self\" rel=\"noopener\">D\u00eda de la expiaci\u00f3n<\/a><\/h4><div class=\"mec-event-detail\">\r\n                        <div class=\"mec-event-loc-place\"><\/div>\r\n                        \r\n                    <\/div><\/div><div style=\"clear:both\"><\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-62-20260909\" data-mec-cell=\"20260909\" ><h6 class=\"mec-table-side-title\">Eventos para septiembre<\/h6><h3 class=\"mec-color mec-table-side-day\"> noveno<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-image\"><\/div><div class=\"mec-monthly-contents\" style=\"width: 100%\"><div class=\"mec-event-time mec-color\"><i class=\"mec-sl-clock-o\"><\/i> 8:00 am - 6:00 pm<\/div><h4 class=\"mec-event-title\"><a class=\"mec-color-hover\" data-event-id=\"18562\" href=\"http:\/\/www.blogtalkradio.com\/gocchurch\" target=\"_self\" rel=\"noopener\">Motor de B\u00fasqueda Internacional<\/a><span class=\"event-color\" style=\"background: #a3b745\"><\/span><\/h4><div class=\"mec-event-detail\">\r\n                        <div class=\"mec-event-loc-place\"><\/div>\r\n                        \r\n                    <\/div><\/div><div style=\"clear:both\"><\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-62-20260910\" data-mec-cell=\"20260910\" ><h6 class=\"mec-table-side-title\">Eventos para septiembre<\/h6><h3 class=\"mec-color mec-table-side-day\"> 10mo<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Sin eventos<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-62-20260911\" data-mec-cell=\"20260911\" ><h6 class=\"mec-table-side-title\">Eventos para septiembre<\/h6><h3 class=\"mec-color mec-table-side-day\"> 11<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-image\"><\/div><div class=\"mec-monthly-contents\" style=\"width: 100%\"><div class=\"mec-event-time mec-color\"><i class=\"mec-sl-clock-o\"><\/i> Evento de todo el d\u00eda<\/div><h4 class=\"mec-event-title\"><a class=\"mec-color-hover\" data-event-id=\"19057\" href=\"https:\/\/gatheringofchrist.org\/es\/events\/coming-out-of-bablyon\/\" target=\"_self\" rel=\"noopener\">Saliendo de Babilonia<\/a><span class=\"event-color\" style=\"background: #a3b745\"><\/span><\/h4><div class=\"mec-event-detail\">\r\n                        <div class=\"mec-event-loc-place\"><\/div>\r\n                        \r\n                    <\/div><\/div><div style=\"clear:both\"><\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-62-20260912\" data-mec-cell=\"20260912\" ><h6 class=\"mec-table-side-title\">Eventos para septiembre<\/h6><h3 class=\"mec-color mec-table-side-day\"> 12<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-image\"><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/gatheringofchrist.org\/wp-content\/uploads\/2021\/04\/AdobeStock_208441509-scaled-e1619172982653-300x300.jpeg\" class=\"attachment-thumblist size-thumblist wp-post-image\" alt=\"\" data-mec-postid=\"18272\" \/><\/div><div class=\"mec-monthly-contents\" style=\"width: calc(100% - 85px)\"><div class=\"mec-event-time mec-color\"><i class=\"mec-sl-clock-o\"><\/i> Evento de todo el d\u00eda<\/div><h4 class=\"mec-event-title\"><a class=\"mec-color-hover\" data-event-id=\"18272\" href=\"https:\/\/gatheringofchrist.org\/es\/events\/feast-of-tabernacles\/\" target=\"_self\" rel=\"noopener\">Fiesta de los Tabern\u00e1culos<\/a><\/h4><div class=\"mec-event-detail\">\r\n                        <div class=\"mec-event-loc-place\"><\/div>\r\n                        \r\n                    <\/div><\/div><div style=\"clear:both\"><\/div><\/article><article class=\"mec-event-article\"><div class=\"mec-event-image\"><\/div><div class=\"mec-monthly-contents\" style=\"width: 100%\"><div class=\"mec-event-time mec-color\"><i class=\"mec-sl-clock-o\"><\/i> Evento de todo el d\u00eda<\/div><h4 class=\"mec-event-title\"><a class=\"mec-color-hover\" data-event-id=\"18558\" href=\"https:\/\/gatheringofchrist.org\/es\/events\/sabbath-class\/\" target=\"_self\" rel=\"noopener\">Clase sab\u00e1tica<\/a><span class=\"event-color\" style=\"background: #fdd700\"><\/span><\/h4><div class=\"mec-event-detail\">\r\n                        <div class=\"mec-event-loc-place\"><\/div>\r\n                        \r\n                    <\/div><\/div><div style=\"clear:both\"><\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-62-20260913\" data-mec-cell=\"20260913\" ><h6 class=\"mec-table-side-title\">Eventos para septiembre<\/h6><h3 class=\"mec-color mec-table-side-day\"> 13<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-image\"><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/gatheringofchrist.org\/wp-content\/uploads\/2021\/04\/AdobeStock_208441509-scaled-e1619172982653-300x300.jpeg\" class=\"attachment-thumblist size-thumblist wp-post-image\" alt=\"\" data-mec-postid=\"18272\" \/><\/div><div class=\"mec-monthly-contents\" style=\"width: calc(100% - 85px)\"><div class=\"mec-event-time mec-color\"><i class=\"mec-sl-clock-o\"><\/i> Evento de todo el d\u00eda<\/div><h4 class=\"mec-event-title\"><a class=\"mec-color-hover\" data-event-id=\"18272\" href=\"https:\/\/gatheringofchrist.org\/es\/events\/feast-of-tabernacles\/\" target=\"_self\" rel=\"noopener\">Fiesta de los Tabern\u00e1culos<\/a><\/h4><div class=\"mec-event-detail\">\r\n                        <div class=\"mec-event-loc-place\"><\/div>\r\n                        \r\n                    <\/div><\/div><div style=\"clear:both\"><\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-62-20260914\" data-mec-cell=\"20260914\" ><h6 class=\"mec-table-side-title\">Eventos para septiembre<\/h6><h3 class=\"mec-color mec-table-side-day\"> 14<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-image\"><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/gatheringofchrist.org\/wp-content\/uploads\/2021\/04\/AdobeStock_208441509-scaled-e1619172982653-300x300.jpeg\" class=\"attachment-thumblist size-thumblist wp-post-image\" alt=\"\" data-mec-postid=\"18272\" \/><\/div><div class=\"mec-monthly-contents\" style=\"width: calc(100% - 85px)\"><div class=\"mec-event-time mec-color\"><i class=\"mec-sl-clock-o\"><\/i> Evento de todo el d\u00eda<\/div><h4 class=\"mec-event-title\"><a class=\"mec-color-hover\" data-event-id=\"18272\" href=\"https:\/\/gatheringofchrist.org\/es\/events\/feast-of-tabernacles\/\" target=\"_self\" rel=\"noopener\">Fiesta de los Tabern\u00e1culos<\/a><\/h4><div class=\"mec-event-detail\">\r\n                        <div class=\"mec-event-loc-place\"><\/div>\r\n                        \r\n                    <\/div><\/div><div style=\"clear:both\"><\/div><\/article><article class=\"mec-event-article\"><div class=\"mec-event-image\"><\/div><div class=\"mec-monthly-contents\" style=\"width: 100%\"><div class=\"mec-event-time mec-color\"><i class=\"mec-sl-clock-o\"><\/i> Evento de todo el d\u00eda<\/div><h4 class=\"mec-event-title\"><a class=\"mec-color-hover\" data-event-id=\"19056\" href=\"https:\/\/gatheringofchrist.org\/es\/events\/restoring-the-daughters-of-zion\/\" target=\"_self\" rel=\"noopener\">Restaurando a las Hijas de Si\u00f3n<\/a><span class=\"event-color\" style=\"background: #a3b745\"><\/span><\/h4><div class=\"mec-event-detail\">\r\n                        <div class=\"mec-event-loc-place\"><\/div>\r\n                        \r\n                    <\/div><\/div><div style=\"clear:both\"><\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-62-20260915\" data-mec-cell=\"20260915\" ><h6 class=\"mec-table-side-title\">Eventos para septiembre<\/h6><h3 class=\"mec-color mec-table-side-day\"> 15<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-image\"><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/gatheringofchrist.org\/wp-content\/uploads\/2021\/04\/AdobeStock_208441509-scaled-e1619172982653-300x300.jpeg\" class=\"attachment-thumblist size-thumblist wp-post-image\" alt=\"\" data-mec-postid=\"18272\" \/><\/div><div class=\"mec-monthly-contents\" style=\"width: calc(100% - 85px)\"><div class=\"mec-event-time mec-color\"><i class=\"mec-sl-clock-o\"><\/i> Evento de todo el d\u00eda<\/div><h4 class=\"mec-event-title\"><a class=\"mec-color-hover\" data-event-id=\"18272\" href=\"https:\/\/gatheringofchrist.org\/es\/events\/feast-of-tabernacles\/\" target=\"_self\" rel=\"noopener\">Fiesta de los Tabern\u00e1culos<\/a><\/h4><div class=\"mec-event-detail\">\r\n                        <div class=\"mec-event-loc-place\"><\/div>\r\n                        \r\n                    <\/div><\/div><div style=\"clear:both\"><\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-62-20260916\" data-mec-cell=\"20260916\" ><h6 class=\"mec-table-side-title\">Eventos para septiembre<\/h6><h3 class=\"mec-color mec-table-side-day\"> 16<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-image\"><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/gatheringofchrist.org\/wp-content\/uploads\/2021\/04\/AdobeStock_208441509-scaled-e1619172982653-300x300.jpeg\" class=\"attachment-thumblist size-thumblist wp-post-image\" alt=\"\" data-mec-postid=\"18272\" \/><\/div><div class=\"mec-monthly-contents\" style=\"width: calc(100% - 85px)\"><div class=\"mec-event-time mec-color\"><i class=\"mec-sl-clock-o\"><\/i> Evento de todo el d\u00eda<\/div><h4 class=\"mec-event-title\"><a class=\"mec-color-hover\" data-event-id=\"18272\" href=\"https:\/\/gatheringofchrist.org\/es\/events\/feast-of-tabernacles\/\" target=\"_self\" rel=\"noopener\">Fiesta de los Tabern\u00e1culos<\/a><\/h4><div class=\"mec-event-detail\">\r\n                        <div class=\"mec-event-loc-place\"><\/div>\r\n                        \r\n                    <\/div><\/div><div style=\"clear:both\"><\/div><\/article><article class=\"mec-event-article\"><div class=\"mec-event-image\"><\/div><div class=\"mec-monthly-contents\" style=\"width: 100%\"><div class=\"mec-event-time mec-color\"><i class=\"mec-sl-clock-o\"><\/i> 8:00 am - 6:00 pm<\/div><h4 class=\"mec-event-title\"><a class=\"mec-color-hover\" data-event-id=\"18562\" href=\"http:\/\/www.blogtalkradio.com\/gocchurch\" target=\"_self\" rel=\"noopener\">Motor de B\u00fasqueda Internacional<\/a><span class=\"event-color\" style=\"background: #a3b745\"><\/span><\/h4><div class=\"mec-event-detail\">\r\n                        <div class=\"mec-event-loc-place\"><\/div>\r\n                        \r\n                    <\/div><\/div><div style=\"clear:both\"><\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-62-20260917\" data-mec-cell=\"20260917\" ><h6 class=\"mec-table-side-title\">Eventos para septiembre<\/h6><h3 class=\"mec-color mec-table-side-day\"> 17<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-image\"><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/gatheringofchrist.org\/wp-content\/uploads\/2021\/04\/AdobeStock_208441509-scaled-e1619172982653-300x300.jpeg\" class=\"attachment-thumblist size-thumblist wp-post-image\" alt=\"\" data-mec-postid=\"18272\" \/><\/div><div class=\"mec-monthly-contents\" style=\"width: calc(100% - 85px)\"><div class=\"mec-event-time mec-color\"><i class=\"mec-sl-clock-o\"><\/i> Evento de todo el d\u00eda<\/div><h4 class=\"mec-event-title\"><a class=\"mec-color-hover\" data-event-id=\"18272\" href=\"https:\/\/gatheringofchrist.org\/es\/events\/feast-of-tabernacles\/\" target=\"_self\" rel=\"noopener\">Fiesta de los Tabern\u00e1culos<\/a><\/h4><div class=\"mec-event-detail\">\r\n                        <div class=\"mec-event-loc-place\"><\/div>\r\n                        \r\n                    <\/div><\/div><div style=\"clear:both\"><\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-62-20260918\" data-mec-cell=\"20260918\" ><h6 class=\"mec-table-side-title\">Eventos para septiembre<\/h6><h3 class=\"mec-color mec-table-side-day\"> 18<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-image\"><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/gatheringofchrist.org\/wp-content\/uploads\/2021\/04\/AdobeStock_208441509-scaled-e1619172982653-300x300.jpeg\" class=\"attachment-thumblist size-thumblist wp-post-image\" alt=\"\" data-mec-postid=\"18272\" \/><\/div><div class=\"mec-monthly-contents\" style=\"width: calc(100% - 85px)\"><div class=\"mec-event-time mec-color\"><i class=\"mec-sl-clock-o\"><\/i> Evento de todo el d\u00eda<\/div><h4 class=\"mec-event-title\"><a class=\"mec-color-hover\" data-event-id=\"18272\" href=\"https:\/\/gatheringofchrist.org\/es\/events\/feast-of-tabernacles\/\" target=\"_self\" rel=\"noopener\">Fiesta de los Tabern\u00e1culos<\/a><\/h4><div class=\"mec-event-detail\">\r\n                        <div class=\"mec-event-loc-place\"><\/div>\r\n                        \r\n                    <\/div><\/div><div style=\"clear:both\"><\/div><\/article><article class=\"mec-event-article\"><div class=\"mec-event-image\"><\/div><div class=\"mec-monthly-contents\" style=\"width: 100%\"><div class=\"mec-event-time mec-color\"><i class=\"mec-sl-clock-o\"><\/i> Evento de todo el d\u00eda<\/div><h4 class=\"mec-event-title\"><a class=\"mec-color-hover\" data-event-id=\"19057\" href=\"https:\/\/gatheringofchrist.org\/es\/events\/coming-out-of-bablyon\/\" target=\"_self\" rel=\"noopener\">Saliendo de Babilonia<\/a><span class=\"event-color\" style=\"background: #a3b745\"><\/span><\/h4><div class=\"mec-event-detail\">\r\n                        <div class=\"mec-event-loc-place\"><\/div>\r\n                        \r\n                    <\/div><\/div><div style=\"clear:both\"><\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-62-20260919\" data-mec-cell=\"20260919\" ><h6 class=\"mec-table-side-title\">Eventos para septiembre<\/h6><h3 class=\"mec-color mec-table-side-day\"> 19<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-image\"><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/gatheringofchrist.org\/wp-content\/uploads\/2021\/04\/AdobeStock_208441509-scaled-e1619172982653-300x300.jpeg\" class=\"attachment-thumblist size-thumblist wp-post-image\" alt=\"\" data-mec-postid=\"18272\" \/><\/div><div class=\"mec-monthly-contents\" style=\"width: calc(100% - 85px)\"><div class=\"mec-event-time mec-color\"><i class=\"mec-sl-clock-o\"><\/i> Evento de todo el d\u00eda<\/div><h4 class=\"mec-event-title\"><a class=\"mec-color-hover\" data-event-id=\"18272\" href=\"https:\/\/gatheringofchrist.org\/es\/events\/feast-of-tabernacles\/\" target=\"_self\" rel=\"noopener\">Fiesta de los Tabern\u00e1culos<\/a><\/h4><div class=\"mec-event-detail\">\r\n                        <div class=\"mec-event-loc-place\"><\/div>\r\n                        \r\n                    <\/div><\/div><div style=\"clear:both\"><\/div><\/article><article class=\"mec-event-article\"><div class=\"mec-event-image\"><\/div><div class=\"mec-monthly-contents\" style=\"width: 100%\"><div class=\"mec-event-time mec-color\"><i class=\"mec-sl-clock-o\"><\/i> Evento de todo el d\u00eda<\/div><h4 class=\"mec-event-title\"><a class=\"mec-color-hover\" data-event-id=\"18558\" href=\"https:\/\/gatheringofchrist.org\/es\/events\/sabbath-class\/\" target=\"_self\" rel=\"noopener\">Clase sab\u00e1tica<\/a><span class=\"event-color\" style=\"background: #fdd700\"><\/span><\/h4><div class=\"mec-event-detail\">\r\n                        <div class=\"mec-event-loc-place\"><\/div>\r\n                        \r\n                    <\/div><\/div><div style=\"clear:both\"><\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-62-20260920\" data-mec-cell=\"20260920\" ><h6 class=\"mec-table-side-title\">Eventos para septiembre<\/h6><h3 class=\"mec-color mec-table-side-day\"> 20<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Sin eventos<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-62-20260921\" data-mec-cell=\"20260921\" ><h6 class=\"mec-table-side-title\">Eventos para septiembre<\/h6><h3 class=\"mec-color mec-table-side-day\"> 21<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-image\"><\/div><div class=\"mec-monthly-contents\" style=\"width: 100%\"><div class=\"mec-event-time mec-color\"><i class=\"mec-sl-clock-o\"><\/i> Evento de todo el d\u00eda<\/div><h4 class=\"mec-event-title\"><a class=\"mec-color-hover\" data-event-id=\"19056\" href=\"https:\/\/gatheringofchrist.org\/es\/events\/restoring-the-daughters-of-zion\/\" target=\"_self\" rel=\"noopener\">Restaurando a las Hijas de Si\u00f3n<\/a><span class=\"event-color\" style=\"background: #a3b745\"><\/span><\/h4><div class=\"mec-event-detail\">\r\n                        <div class=\"mec-event-loc-place\"><\/div>\r\n                        \r\n                    <\/div><\/div><div style=\"clear:both\"><\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-62-20260922\" data-mec-cell=\"20260922\" ><h6 class=\"mec-table-side-title\">Eventos para septiembre<\/h6><h3 class=\"mec-color mec-table-side-day\"> 22<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Sin eventos<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-62-20260923\" data-mec-cell=\"20260923\" ><h6 class=\"mec-table-side-title\">Eventos para septiembre<\/h6><h3 class=\"mec-color mec-table-side-day\"> 23<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-image\"><\/div><div class=\"mec-monthly-contents\" style=\"width: 100%\"><div class=\"mec-event-time mec-color\"><i class=\"mec-sl-clock-o\"><\/i> 8:00 am - 6:00 pm<\/div><h4 class=\"mec-event-title\"><a class=\"mec-color-hover\" data-event-id=\"18562\" href=\"http:\/\/www.blogtalkradio.com\/gocchurch\" target=\"_self\" rel=\"noopener\">Motor de B\u00fasqueda Internacional<\/a><span class=\"event-color\" style=\"background: #a3b745\"><\/span><\/h4><div class=\"mec-event-detail\">\r\n                        <div class=\"mec-event-loc-place\"><\/div>\r\n                        \r\n                    <\/div><\/div><div style=\"clear:both\"><\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-62-20260924\" data-mec-cell=\"20260924\" ><h6 class=\"mec-table-side-title\">Eventos para septiembre<\/h6><h3 class=\"mec-color mec-table-side-day\"> 24<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Sin eventos<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-62-20260925\" data-mec-cell=\"20260925\" ><h6 class=\"mec-table-side-title\">Eventos para septiembre<\/h6><h3 class=\"mec-color mec-table-side-day\"> 25<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-image\"><\/div><div class=\"mec-monthly-contents\" style=\"width: 100%\"><div class=\"mec-event-time mec-color\"><i class=\"mec-sl-clock-o\"><\/i> Evento de todo el d\u00eda<\/div><h4 class=\"mec-event-title\"><a class=\"mec-color-hover\" data-event-id=\"19057\" href=\"https:\/\/gatheringofchrist.org\/es\/events\/coming-out-of-bablyon\/\" target=\"_self\" rel=\"noopener\">Saliendo de Babilonia<\/a><span class=\"event-color\" style=\"background: #a3b745\"><\/span><\/h4><div class=\"mec-event-detail\">\r\n                        <div class=\"mec-event-loc-place\"><\/div>\r\n                        \r\n                    <\/div><\/div><div style=\"clear:both\"><\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-62-20260926\" data-mec-cell=\"20260926\" ><h6 class=\"mec-table-side-title\">Eventos para septiembre<\/h6><h3 class=\"mec-color mec-table-side-day\"> 26<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-image\"><\/div><div class=\"mec-monthly-contents\" style=\"width: 100%\"><div class=\"mec-event-time mec-color\"><i class=\"mec-sl-clock-o\"><\/i> Evento de todo el d\u00eda<\/div><h4 class=\"mec-event-title\"><a class=\"mec-color-hover\" data-event-id=\"18558\" href=\"https:\/\/gatheringofchrist.org\/es\/events\/sabbath-class\/\" target=\"_self\" rel=\"noopener\">Clase sab\u00e1tica<\/a><span class=\"event-color\" style=\"background: #fdd700\"><\/span><\/h4><div class=\"mec-event-detail\">\r\n                        <div class=\"mec-event-loc-place\"><\/div>\r\n                        \r\n                    <\/div><\/div><div style=\"clear:both\"><\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-62-20260927\" data-mec-cell=\"20260927\" ><h6 class=\"mec-table-side-title\">Eventos para septiembre<\/h6><h3 class=\"mec-color mec-table-side-day\"> 27<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Sin eventos<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-62-20260928\" data-mec-cell=\"20260928\" ><h6 class=\"mec-table-side-title\">Eventos para septiembre<\/h6><h3 class=\"mec-color mec-table-side-day\"> 28<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-image\"><\/div><div class=\"mec-monthly-contents\" style=\"width: 100%\"><div class=\"mec-event-time mec-color\"><i class=\"mec-sl-clock-o\"><\/i> Evento de todo el d\u00eda<\/div><h4 class=\"mec-event-title\"><a class=\"mec-color-hover\" data-event-id=\"19056\" href=\"https:\/\/gatheringofchrist.org\/es\/events\/restoring-the-daughters-of-zion\/\" target=\"_self\" rel=\"noopener\">Restaurando a las Hijas de Si\u00f3n<\/a><span class=\"event-color\" style=\"background: #a3b745\"><\/span><\/h4><div class=\"mec-event-detail\">\r\n                        <div class=\"mec-event-loc-place\"><\/div>\r\n                        \r\n                    <\/div><\/div><div style=\"clear:both\"><\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-62-20260929\" data-mec-cell=\"20260929\" ><h6 class=\"mec-table-side-title\">Eventos para septiembre<\/h6><h3 class=\"mec-color mec-table-side-day\"> 29<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-detail\">Sin eventos<\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-62-20260930\" data-mec-cell=\"20260930\" ><h6 class=\"mec-table-side-title\">Eventos para septiembre<\/h6><h3 class=\"mec-color mec-table-side-day\"> 30<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-image\"><\/div><div class=\"mec-monthly-contents\" style=\"width: 100%\"><div class=\"mec-event-time mec-color\"><i class=\"mec-sl-clock-o\"><\/i> 8:00 am - 6:00 pm<\/div><h4 class=\"mec-event-title\"><a class=\"mec-color-hover\" data-event-id=\"18562\" href=\"http:\/\/www.blogtalkradio.com\/gocchurch\" target=\"_self\" rel=\"noopener\">Motor de B\u00fasqueda Internacional<\/a><span class=\"event-color\" style=\"background: #a3b745\"><\/span><\/h4><div class=\"mec-event-detail\">\r\n                        <div class=\"mec-event-loc-place\"><\/div>\r\n                        \r\n                    <\/div><\/div><div style=\"clear:both\"><\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-62-20261002\" data-mec-cell=\"20261002\" ><h6 class=\"mec-table-side-title\">Eventos para octubre<\/h6><h3 class=\"mec-color mec-table-side-day\"> 2do<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-image\"><\/div><div class=\"mec-monthly-contents\" style=\"width: 100%\"><div class=\"mec-event-time mec-color\"><i class=\"mec-sl-clock-o\"><\/i> Evento de todo el d\u00eda<\/div><h4 class=\"mec-event-title\"><a class=\"mec-color-hover\" data-event-id=\"19057\" href=\"https:\/\/gatheringofchrist.org\/es\/events\/coming-out-of-bablyon\/\" target=\"_self\" rel=\"noopener\">Saliendo de Babilonia<\/a><span class=\"event-color\" style=\"background: #a3b745\"><\/span><\/h4><div class=\"mec-event-detail\">\r\n                            <div class=\"mec-event-loc-place\"><\/div>\r\n                            \r\n                        <\/div><\/div><div style=\"clear:both\"><\/div><\/article><\/div><div class=\"mec-calendar-events-sec\" id=\"mec-calendar-events-sec-62-20261003\" data-mec-cell=\"20261003\" ><h6 class=\"mec-table-side-title\">Eventos para octubre<\/h6><h3 class=\"mec-color mec-table-side-day\"> 3er<\/h3><article class=\"mec-event-article\"><div class=\"mec-event-image\"><\/div><div class=\"mec-monthly-contents\" style=\"width: 100%\"><div class=\"mec-event-time mec-color\"><i class=\"mec-sl-clock-o\"><\/i> Evento de todo el d\u00eda<\/div><h4 class=\"mec-event-title\"><a class=\"mec-color-hover\" data-event-id=\"18558\" href=\"https:\/\/gatheringofchrist.org\/es\/events\/sabbath-class\/\" target=\"_self\" rel=\"noopener\">Clase sab\u00e1tica<\/a><span class=\"event-color\" style=\"background: #fdd700\"><\/span><\/h4><div class=\"mec-event-detail\">\r\n                            <div class=\"mec-event-loc-place\"><\/div>\r\n                            \r\n                        <\/div><\/div><div style=\"clear:both\"><\/div><\/article><\/div><\/div><\/div><\/div><div class=\"mec-event-footer\"><\/div>    <\/div>\r\n\r\n        \r\n        <div class=\"mec-modal-result\"><\/div>\r\n\r\n<\/div>    <\/div>\r\n\r\n    <\/div>\r\n\n<\/div><\/div><\/div><\/div><\/div><\/div><script id=\"script-row-unique-0\" data-row=\"script-row-unique-0\" type=\"text\/javascript\" class=\"vc_controls\">UNCODE.initRow(document.getElementById(\"row-unique-0\"));<\/script><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"Watch sabbath class live every Saturday Weekly Sabbath Classes are live every Saturday at 11:30 AM NY Time, you can [...]","protected":false},"author":1,"featured_media":18478,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"nf_dc_page":"","footnotes":""},"class_list":["post-78","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/gatheringofchrist.org\/es\/wp-json\/wp\/v2\/pages\/78","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gatheringofchrist.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/gatheringofchrist.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/gatheringofchrist.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gatheringofchrist.org\/es\/wp-json\/wp\/v2\/comments?post=78"}],"version-history":[{"count":3,"href":"https:\/\/gatheringofchrist.org\/es\/wp-json\/wp\/v2\/pages\/78\/revisions"}],"predecessor-version":[{"id":18758,"href":"https:\/\/gatheringofchrist.org\/es\/wp-json\/wp\/v2\/pages\/78\/revisions\/18758"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gatheringofchrist.org\/es\/wp-json\/wp\/v2\/media\/18478"}],"wp:attachment":[{"href":"https:\/\/gatheringofchrist.org\/es\/wp-json\/wp\/v2\/media?parent=78"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}